{"id":36,"count":44,"description":"","link":"https:\/\/new.ldsfriend.com\/uk\/category\/apologetic\/church\/doctrine\/","name":"\u0423\u0447\u0435\u043d\u0438\u0435","slug":"doctrine","taxonomy":"category","parent":21,"meta":[],"_links":{"self":[{"href":"https:\/\/new.ldsfriend.com\/uk\/wp-json\/wp\/v2\/categories\/36","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.ldsfriend.com\/uk\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/new.ldsfriend.com\/uk\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/new.ldsfriend.com\/uk\/wp-json\/wp\/v2\/categories\/21"}],"wp:post_type":[{"href":"https:\/\/new.ldsfriend.com\/uk\/wp-json\/wp\/v2\/posts?categories=36"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}