{"id":5,"count":1,"description":"","link":"https:\/\/new.ldsfriend.com\/uk\/category\/mobile\/","name":"Mobile","slug":"mobile","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/new.ldsfriend.com\/uk\/wp-json\/wp\/v2\/categories\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.ldsfriend.com\/uk\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/new.ldsfriend.com\/uk\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/new.ldsfriend.com\/uk\/wp-json\/wp\/v2\/posts?categories=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}