{"id":7,"count":8,"description":"Sharing creative stuff about web design.","link":"https:\/\/new.ldsfriend.com\/uk\/category\/web-design\/","name":"Web Design","slug":"web-design","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/new.ldsfriend.com\/uk\/wp-json\/wp\/v2\/categories\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.ldsfriend.com\/uk\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/new.ldsfriend.com\/uk\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/new.ldsfriend.com\/uk\/wp-json\/wp\/v2\/posts?categories=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}